{"id":269,"date":"2026-02-26T18:51:49","date_gmt":"2026-02-26T10:51:49","guid":{"rendered":"https:\/\/www.kurzvape.de\/?page_id=269"},"modified":"2026-07-06T10:38:59","modified_gmt":"2026-07-06T08:38:59","slug":"rueckgaberichtlinie","status":"publish","type":"page","link":"https:\/\/www.kurzvape.de\/it\/rueckgaberichtlinie\/","title":{"rendered":"Politica di restituzione"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Politica di restituzione - short vape<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Diritto di recesso di 3 giorni<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con kurzvape vi garantiamo un diritto di recesso di tre giorni. Dal giorno in cui ricevete la merce, avete tre giorni di tempo per richiedere un reso se non siete soddisfatti dell'articolo ricevuto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Requisiti per la restituzione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Affinch\u00e9 un reso venga riconosciuto, l'articolo deve essere nelle esatte condizioni in cui \u00e8 stato consegnato: non aperto, non usato, con tutte le etichette originali attaccate e nella sua confezione originale e non danneggiata. Si prega inoltre di tenere a portata di mano la prova d'acquisto o la ricevuta, che sar\u00e0 necessaria per elaborare il reso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Come avviare una restituzione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per avviare una procedura di reso, vi preghiamo di contattarci all'indirizzo info@kurzvape.de. Una volta esaminata e approvata la vostra richiesta, vi forniremo un'etichetta di reso preaffrancata e istruzioni dettagliate su come e dove spedire il pacco. Attenzione: i resi che ci pervengono senza previa autorizzazione non saranno accettati. Vi preghiamo quindi di contattarci prima di procedere.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Merce danneggiata o difettosa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vi consigliamo di controllare attentamente il vostro ordine non appena lo ricevete. Se notate che un articolo \u00e8 arrivato danneggiato, presenta un difetto o non corrisponde al vostro ordine, vi preghiamo di contattarci immediatamente in modo da poter risolvere il problema il pi\u00f9 rapidamente possibile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Articoli esclusi dalla restituzione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Non tutti i prodotti possono essere restituiti. Fanno eccezione i prodotti deperibili, i prodotti personalizzati, gli articoli per l'igiene e le sostanze pericolose come liquidi o gas infiammabili. Se non siete sicuri che un determinato articolo possa essere restituito, contattateci in anticipo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Scambio di articoli<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per la sostituzione consigliamo la seguente procedura: In primo luogo, inviateci l'articolo originale. Non appena il reso sar\u00e0 autorizzato da noi, potrete inserire l'articolo sostitutivo desiderato in un nuovo ordine. In questo modo possiamo garantire un'elaborazione rapida e senza intoppi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Elaborazione dei rimborsi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Non appena avremo ricevuto e verificato il vostro reso, vi informeremo sullo stato di elaborazione della vostra richiesta di rimborso. In caso di esito positivo della verifica, il rimborso verr\u00e0 effettuato sul metodo di pagamento originariamente utilizzato entro 10 giorni lavorativi. La preghiamo di tenere presente che la sua banca o l\u2019emittente della sua carta di credito potrebbero richiedere ulteriore tempo per l\u2019accredito definitivo. Qualora il rimborso non fosse ancora stato accreditato sul suo conto dopo 15 giorni lavorativi dall\u2019approvazione, la preghiamo di contattarci nuovamente all\u2019indirizzo info@kurzvape.de.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie per la vostra fiducia in kurzvape. La vostra soddisfazione \u00e8 la nostra massima priorit\u00e0.<\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00fcckgaberichtlinie \u2013 kurzvape 3-t\u00e4giges R\u00fcckgaberecht Bei kurzvape r\u00e4umen wir Ihnen ein dreit\u00e4giges R\u00fcckgaberecht ein. Ab dem Tag, an dem Ihre Ware bei Ihnen eintrifft, haben Sie drei Tage Zeit, eine R\u00fcckgabe zu beantragen, sofern Sie mit dem erhaltenen Artikel nicht zufrieden sind. Voraussetzungen f\u00fcr eine R\u00fcckgabe Damit eine R\u00fcckgabe anerkannt werden kann, muss sich der [&#8230;]\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-269","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/pages\/269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/comments?post=269"}],"version-history":[{"count":1,"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/pages\/269\/revisions"}],"predecessor-version":[{"id":6494,"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/pages\/269\/revisions\/6494"}],"wp:attachment":[{"href":"https:\/\/www.kurzvape.de\/it\/wp-json\/wp\/v2\/media?parent=269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}